{"id":1380,"date":"2018-10-31T15:41:41","date_gmt":"2018-10-31T15:41:41","guid":{"rendered":"https:\/\/symplify.com\/non-classifiee\/no-more-gdpr-headache\/"},"modified":"2026-01-22T14:20:18","modified_gmt":"2026-01-22T14:20:18","slug":"no-more-gdpr-headache","status":"publish","type":"post","link":"https:\/\/symplify.com\/fr\/blog\/no-more-gdpr-headache\/","title":{"rendered":"Finis les maux de t\u00eate li\u00e9s au RGPD"},"content":{"rendered":"<p>Toujours stress\u00e9 par le RGPD ? Prenez une grande inspiration de yoga et faites confiance \u00e0 la puissance de Symplify. Nous offrons huit (!) canaux sur UNE SEULE plateforme pour simplifier la protection des donn\u00e9es personnelles sur votre lieu de travail. Cela signifie litt\u00e9ralement que tous les d\u00e9sabonnements sont vers\u00e9s dans UNE SEULE base de donn\u00e9es en temps r\u00e9el et s&rsquo;appliquent imm\u00e9diatement \u00e0 tous les canaux. Tout sous le m\u00eame toit. Sympa, non ?<\/p>\n<p>Nous croyons en la simplicit\u00e9 de tout, litt\u00e9ralement tout. M\u00eame ce r\u00e8glement \u00ab d&rsquo;abord difficile \u00e0 manier, mais qui s&rsquo;est av\u00e9r\u00e9 plut\u00f4t bon \u00bb qui prot\u00e8ge notre int\u00e9grit\u00e9 comme jamais auparavant.<\/p>\n<p>Avec Symplify, vous b\u00e9n\u00e9ficiez d&rsquo;une protection unique des donn\u00e9es personnelles gr\u00e2ce \u00e0 notre plateforme multicanal, ce qui vous permet de vous d\u00e9tendre et d&rsquo;\u00eatre s\u00fbr que toutes vos donn\u00e9es personnelles sont prot\u00e9g\u00e9es en toute s\u00e9curit\u00e9.<\/p>\n<p>Afin que vous soyez totalement conforme au RGPD, voici quelques points importants que nous souhaitons vous rappeler lorsque vous cr\u00e9ez de la magie :<\/p>\n<ol role=\"list\">\n<li><strong>Le consentement requiert un opt-in positif.<\/strong> Les cases pr\u00e9-coch\u00e9es sont \u00e0 proscrire.<\/li>\n<li><strong>S\u00e9parez les demandes de consentement des autres conditions g\u00e9n\u00e9rales.<\/strong><\/li>\n<li><strong>Facilitez le retrait du consentement<\/strong> \u2013 et indiquez aux personnes comment proc\u00e9der (pas seulement parce que c&rsquo;est une bonne chose \u00e0 faire, mais aussi parce que c&rsquo;est obligatoire).<\/li>\n<li><strong>V\u00e9rifiez-vous avant de vous planter !<\/strong> C&rsquo;est-\u00e0-dire, v\u00e9rifiez vos pratiques de consentement et les consentements existants. Et une fois que vous avez termin\u00e9, offrez-vous un grand latte (peut-\u00eatre d\u00e9caf\u00e9in\u00e9).<\/li>\n<li><strong>Qui, quand, comment \u2013 conservez une preuve du consentement. <\/strong>Cela signifie que vous serez en mesure de dire :<\/li>\n<\/ol>\n<ul role=\"list\">\n<li>Qui a consenti<\/li>\n<li>Quand a-t-il consenti<\/li>\n<li>Ce qui leur a \u00e9t\u00e9 dit lorsqu&rsquo;ils ont consenti<\/li>\n<li>S&rsquo;ils ont retir\u00e9 leur consentement ou non. Si oui, quand ?<\/li>\n<li>Comment ils ont consenti (via Facebook, lors d&rsquo;un paiement, etc.)<\/li>\n<\/ul>\n<p>Si vous \u00eates toujours stress\u00e9 par cela et que vous voulez savoir ce que cela signifie r\u00e9ellement pour vous et votre entreprise, contactez-nous et nous vous aiderons.<\/p>\n<p>Enfin, et surtout, restez calme et soyez conforme au RGPD !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Toujours stress\u00e9 par le RGPD ? Prenez une grande inspiration de yoga et faites confiance \u00e0 la puissance de Symplify.  [&#8230;]<\/p>\n","protected":false},"author":5,"featured_media":1332,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[28,29],"tags":[],"class_list":["post-1380","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-communication-fr"],"_links":{"self":[{"href":"https:\/\/symplify.com\/fr\/wp-json\/wp\/v2\/posts\/1380","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/symplify.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/symplify.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/symplify.com\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/symplify.com\/fr\/wp-json\/wp\/v2\/comments?post=1380"}],"version-history":[{"count":2,"href":"https:\/\/symplify.com\/fr\/wp-json\/wp\/v2\/posts\/1380\/revisions"}],"predecessor-version":[{"id":12955,"href":"https:\/\/symplify.com\/fr\/wp-json\/wp\/v2\/posts\/1380\/revisions\/12955"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/symplify.com\/fr\/wp-json\/wp\/v2\/media\/1332"}],"wp:attachment":[{"href":"https:\/\/symplify.com\/fr\/wp-json\/wp\/v2\/media?parent=1380"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/symplify.com\/fr\/wp-json\/wp\/v2\/categories?post=1380"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/symplify.com\/fr\/wp-json\/wp\/v2\/tags?post=1380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}